{"id":12560,"date":"2026-09-02T09:34:45","date_gmt":"2026-09-02T07:34:45","guid":{"rendered":"https:\/\/cyrkus.eu\/?page_id=12560"},"modified":"2026-09-02T09:34:47","modified_gmt":"2026-09-02T07:34:47","slug":"grupa-performerska","status":"publish","type":"page","link":"https:\/\/cyrkus.eu\/pl\/grupa-performerska\/","title":{"rendered":"Grupa performerska"},"content":{"rendered":"\n<div class=\"breit Ueberschrift-Titel\">\n<h1 class=\"wp-block-heading\">Grupa performerska<\/h1>\n<\/div>\n\n\n\n<div class=\"breit Container-Durchsichtig\">\n<div class=\"gb-element-73ab77e7\">\n<div>\n<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\" title=\"Performance-Grup\" alt=\"\" srcset=\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg 1024w, https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup-800x800.jpg 800w, https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup-340x340.jpg 340w, https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup-768x768.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n<\/div>\n\n\n\n<div>\n<p class=\"wp-block-paragraph\">Grupa Performerska to warsztat skierowany do dzieci i m\u0142odzie\u017cy, kt\u00f3re maj\u0105 ju\u017c do\u015bwiadczenie w sztukach cyrkowych i marz\u0105 o tym, by zab\u0142ysn\u0105\u0107 na scenie. Podczas zaj\u0119\u0107 uczestnicy wsp\u00f3lnie pracuj\u0105 nad tworzeniem i przygotowywaniem wyst\u0119p\u00f3w cyrkowych, rozwijaj\u0105c swoje umiej\u0119tno\u015bci techniczne, sceniczne i artystyczne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Praca w grupie koncentruje si\u0119 na jako\u015bci, precyzji i kunszcie sztuki cyrkowej, a tak\u017ce na budowaniu zespo\u0142owej energii i scenicznej obecno\u015bci. To przestrze\u0144 dla m\u0142odych artyst\u00f3w, kt\u00f3rzy chc\u0105 stawia\u0107 sobie nowe wyzwania, rozwija\u0107 w\u0142asny styl i do\u015bwiadcza\u0107 cyrku jako pe\u0142noprawnej sztuki scenicznej.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zapisy na sezon 2026\/2027 odbywa si\u0119 za po\u015brednictwem naszego formularza:<br><a href=\"https:\/\/cyrkus.eu\/pl\/?page_id=12317\">Przejd\u017a do formularza zg\u0142oszeniowego (dost\u0119pny od 7 wrze\u015bnia 2026 r. o godz. 8:00)<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"breit Container-Orange\">\n<div  class=\"tribe-compatibility-container\" >\n\t<div\n\t\t class=\"tribe-common tribe-events tribe-events-view tribe-events-view--widget-events-list tribe-events-widget\" \t\tdata-js=\"tribe-events-view\"\n\t\tdata-view-rest-url=\"https:\/\/cyrkus.eu\/pl\/wp-json\/tribe\/views\/v2\/html\"\n\t\tdata-view-manage-url=\"1\"\n\t\t\t\t\t\t\tdata-view-breakpoint-pointer=\"92116ed2-e88b-49a7-b34f-5ad72390eae3\"\n\t\t\t>\n\t\t<div class=\"tribe-events-widget-events-list\">\n\n\t\t\t<script type=\"application\/ld+json\">\r\n[{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"CYRKUS-TYDZIE\\u0143 OTWARTYCH DRZWI\",\"description\":\"&lt;p&gt;Kiedy? Tydzie\\u0144 otwartych drzwi w dniach 7\\u201311.2026 r., w godz. od 15:00 do 18:30, odb\\u0119dzie ... &lt;a title=&quot;CYRKUS-TYDZIE\\u0143 OTWARTYCH DRZWI&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/cyrkus-schnupperwoche\/2026-09-07\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o CYRKUS-TYDZIE\\u0143 OTWARTYCH DRZWI&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/schnupperwoche.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/cyrkus-schnupperwoche\/2026-09-07\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-07T15:00:00+02:00\",\"endDate\":\"2026-09-07T18:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"CYRKUS-TYDZIE\\u0143 OTWARTYCH DRZWI\",\"description\":\"&lt;p&gt;Kiedy? Tydzie\\u0144 otwartych drzwi w dniach 7\\u201311.2026 r., w godz. od 15:00 do 18:30, odb\\u0119dzie ... &lt;a title=&quot;CYRKUS-TYDZIE\\u0143 OTWARTYCH DRZWI&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/cyrkus-schnupperwoche\/2026-09-08\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o CYRKUS-TYDZIE\\u0143 OTWARTYCH DRZWI&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/schnupperwoche.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/cyrkus-schnupperwoche\/2026-09-08\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-08T15:00:00+02:00\",\"endDate\":\"2026-09-08T18:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"CYRKUS-TYDZIE\\u0143 OTWARTYCH DRZWI\",\"description\":\"&lt;p&gt;Kiedy? Tydzie\\u0144 otwartych drzwi w dniach 7\\u201311.2026 r., w godz. od 15:00 do 18:30, odb\\u0119dzie ... &lt;a title=&quot;CYRKUS-TYDZIE\\u0143 OTWARTYCH DRZWI&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/cyrkus-schnupperwoche\/2026-09-09\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o CYRKUS-TYDZIE\\u0143 OTWARTYCH DRZWI&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/schnupperwoche.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/cyrkus-schnupperwoche\/2026-09-09\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-09T15:00:00+02:00\",\"endDate\":\"2026-09-09T18:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"CYRKUS-TYDZIE\\u0143 OTWARTYCH DRZWI\",\"description\":\"&lt;p&gt;Kiedy? Tydzie\\u0144 otwartych drzwi w dniach 7\\u201311.2026 r., w godz. od 15:00 do 18:30, odb\\u0119dzie ... &lt;a title=&quot;CYRKUS-TYDZIE\\u0143 OTWARTYCH DRZWI&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/cyrkus-schnupperwoche\/2026-09-10\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o CYRKUS-TYDZIE\\u0143 OTWARTYCH DRZWI&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/schnupperwoche.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/cyrkus-schnupperwoche\/2026-09-10\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-10T15:00:00+02:00\",\"endDate\":\"2026-09-10T18:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"CYRKUS-TYDZIE\\u0143 OTWARTYCH DRZWI\",\"description\":\"&lt;p&gt;Kiedy? Tydzie\\u0144 otwartych drzwi w dniach 7\\u201311.2026 r., w godz. od 15:00 do 18:30, odb\\u0119dzie ... &lt;a title=&quot;CYRKUS-TYDZIE\\u0143 OTWARTYCH DRZWI&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/cyrkus-schnupperwoche\/2026-09-11\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o CYRKUS-TYDZIE\\u0143 OTWARTYCH DRZWI&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/schnupperwoche.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/cyrkus-schnupperwoche\/2026-09-11\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-11T15:00:00+02:00\",\"endDate\":\"2026-09-11T18:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-09-14\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-09-14\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-14T17:30:00+02:00\",\"endDate\":\"2026-09-14T19:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-09-21\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-09-21\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-21T17:30:00+02:00\",\"endDate\":\"2026-09-21T19:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-09-28\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-09-28\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-28T17:30:00+02:00\",\"endDate\":\"2026-09-28T19:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-10-05\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-10-05\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-10-05T17:30:00+02:00\",\"endDate\":\"2026-10-05T19:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-10-26\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-10-26\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-10-26T17:30:00+01:00\",\"endDate\":\"2026-10-26T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-11-02\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-11-02\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-11-02T17:30:00+01:00\",\"endDate\":\"2026-11-02T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-11-09\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-11-09\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-11-09T17:30:00+01:00\",\"endDate\":\"2026-11-09T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-11-16\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-11-16\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-11-16T17:30:00+01:00\",\"endDate\":\"2026-11-16T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-11-23\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-11-23\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-11-23T17:30:00+01:00\",\"endDate\":\"2026-11-23T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-11-30\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-11-30\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-11-30T17:30:00+01:00\",\"endDate\":\"2026-11-30T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-12-07\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-12-07\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-12-07T17:30:00+01:00\",\"endDate\":\"2026-12-07T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-01-11\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-01-11\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2027-01-11T17:30:00+01:00\",\"endDate\":\"2027-01-11T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-01-18\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-01-18\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2027-01-18T17:30:00+01:00\",\"endDate\":\"2027-01-18T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-01-25\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-01-25\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2027-01-25T17:30:00+01:00\",\"endDate\":\"2027-01-25T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-02-01\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-02-01\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2027-02-01T17:30:00+01:00\",\"endDate\":\"2027-02-01T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-02-22\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-02-22\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2027-02-22T17:30:00+01:00\",\"endDate\":\"2027-02-22T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-03-01\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-03-01\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2027-03-01T17:30:00+01:00\",\"endDate\":\"2027-03-01T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-03-08\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-03-08\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2027-03-08T17:30:00+01:00\",\"endDate\":\"2027-03-08T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-03-15\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-03-15\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2027-03-15T17:30:00+01:00\",\"endDate\":\"2027-03-15T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-03-22\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-03-22\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2027-03-22T17:30:00+01:00\",\"endDate\":\"2027-03-22T19:30:00+01:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-04-05\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-04-05\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2027-04-05T17:30:00+02:00\",\"endDate\":\"2027-04-05T19:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-04-12\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-04-12\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2027-04-12T17:30:00+02:00\",\"endDate\":\"2027-04-12T19:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-04-19\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-04-19\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2027-04-19T17:30:00+02:00\",\"endDate\":\"2027-04-19T19:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-04-26\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-04-26\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2027-04-26T17:30:00+02:00\",\"endDate\":\"2027-04-26T19:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-05-03\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-05-03\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2027-05-03T17:30:00+02:00\",\"endDate\":\"2027-05-03T19:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Grupa performerska\",\"description\":\"&lt;p&gt;Grupa Performerska to warsztat skierowany do dzieci i m\\u0142odzie\\u017cy, kt\\u00f3re maj\\u0105 ju\\u017c do\\u015bwiadczenie w sztukach ... &lt;a title=&quot;Grupa performerska&quot; class=&quot;read-more&quot; href=&quot;https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-05-10\/&quot; aria-label=&quot;Dowiedz si\\u0119 wi\\u0119cej o Grupa performerska&quot;&gt;Czytaj dalej&lt;\/a&gt;&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/cyrkus.eu\/wp-content\/uploads\/2026\/08\/performance-grup.jpg\",\"url\":\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-05-10\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2027-05-10T17:30:00+02:00\",\"endDate\":\"2027-05-10T19:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"CYRKUS DOMicil\",\"description\":\"\",\"url\":\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Conrad-Schiedt-Stra\\u00dfe 20\",\"addressLocality\":\"G\\u00f6rlitz\",\"addressRegion\":\"Sachsen\",\"postalCode\":\"02826\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"KulturBr\\u00fccken G\\u00f6rlitz e.V.\",\"description\":\"\",\"url\":\"http:\/\/kulturbruecken.eu\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"http:\/\/kulturbruecken.eu\"},\"performer\":\"Organization\"}]\r\n<\/script>\n\t\t\t<script data-js=\"tribe-events-view-data\" type=\"application\/json\">\n\t{\"slug\":\"widget-events-list\",\"prev_url\":\"\",\"next_url\":\"\",\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Widgets\\\\Widget_List_View\",\"view_slug\":\"widget-events-list\",\"view_label\":\"View\",\"view\":null,\"should_manage_url\":true,\"id\":null,\"alias-slugs\":null,\"title\":\"Wydarzenia z 7. wrze\\u015bnia \\u2013 10. maja 2027 \\u2013 CYRKUS\",\"limit\":\"100\",\"no_upcoming_events\":true,\"featured_events_only\":false,\"jsonld_enable\":true,\"tribe_is_list_widget\":false,\"admin_fields\":{\"title\":{\"label\":\"Nazwa:\",\"type\":\"text\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-title\",\"name\":\"widget-tribe-widget-events-list[-1][title]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"limit\":{\"label\":\"Poka\\u017c:\",\"type\":\"number\",\"default\":5,\"min\":1,\"max\":10,\"step\":1,\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-limit\",\"name\":\"widget-tribe-widget-events-list[-1][limit]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"metadata_section\":{\"type\":\"fieldset\",\"classes\":\"tribe-common-form-control-checkbox-checkbox-group\",\"label\":\"Display:\",\"children\":{\"cost\":{\"type\":\"checkbox\",\"label\":\"Cena\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-cost\",\"name\":\"widget-tribe-widget-events-list[-1][cost]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"venue\":{\"type\":\"checkbox\",\"label\":\"Miejsce\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-venue\",\"name\":\"widget-tribe-widget-events-list[-1][venue]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"street\":{\"type\":\"checkbox\",\"label\":\"Ulica\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-street\",\"name\":\"widget-tribe-widget-events-list[-1][street]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"city\":{\"type\":\"checkbox\",\"label\":\"Miasto\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-city\",\"name\":\"widget-tribe-widget-events-list[-1][city]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"region\":{\"type\":\"checkbox\",\"label\":\"Stan (USA) Lub Wojew\\u00f3dztwo\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-region\",\"name\":\"widget-tribe-widget-events-list[-1][region]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"zip\":{\"type\":\"checkbox\",\"label\":\"Kod pocztowy\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-zip\",\"name\":\"widget-tribe-widget-events-list[-1][zip]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"country\":{\"type\":\"checkbox\",\"label\":\"Kraj\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-country\",\"name\":\"widget-tribe-widget-events-list[-1][country]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"phone\":{\"type\":\"checkbox\",\"label\":\"Telefon\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-phone\",\"name\":\"widget-tribe-widget-events-list[-1][phone]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"organizer\":{\"type\":\"checkbox\",\"label\":\"Organizator\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-organizer\",\"name\":\"widget-tribe-widget-events-list[-1][organizer]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"website\":{\"type\":\"checkbox\",\"label\":\"Website\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-website\",\"name\":\"widget-tribe-widget-events-list[-1][website]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-metadata_section\",\"name\":\"widget-tribe-widget-events-list[-1][metadata_section]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"taxonomy_section\":{\"type\":\"section\",\"classes\":[\"calendar-widget-filters-container\"],\"label\":\"Filtry:\",\"children\":{\"filters\":{\"type\":\"taxonomy-filters\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-filters\",\"label\":\"\",\"name\":\"widget-tribe-widget-events-list[-1][filters]\",\"options\":[],\"placeholder\":\"\",\"value\":null,\"list_items\":[]},\"operand\":{\"type\":\"fieldset\",\"classes\":\"tribe-common-form-control-checkbox-radio-group\",\"label\":\"Operand:\",\"selected\":\"OR\",\"children\":[{\"type\":\"radio\",\"label\":\"Match any\",\"button_value\":\"OR\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-operand\",\"name\":\"widget-tribe-widget-events-list[-1][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null},{\"type\":\"radio\",\"label\":\"Match all\",\"button_value\":\"AND\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-operand\",\"name\":\"widget-tribe-widget-events-list[-1][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null}],\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-operand\",\"name\":\"widget-tribe-widget-events-list[-1][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-taxonomy_section\",\"name\":\"widget-tribe-widget-events-list[-1][taxonomy_section]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"taxonomy\":{\"type\":\"taxonomy\",\"classes\":\"calendar-widget-add-filter\",\"label\":\"Dodaj filtr:\",\"placeholder\":\"Select a Taxonomy Term\",\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-taxonomy\",\"name\":\"widget-tribe-widget-events-list[-1][taxonomy]\",\"options\":[],\"value\":null},\"no_upcoming_events\":{\"label\":\"Ukryj ten wid\\u017cet, je\\u015bli nie ma nadchodz\\u0105cych wydarze\\u0144.\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-no_upcoming_events\",\"name\":\"widget-tribe-widget-events-list[-1][no_upcoming_events]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"featured_events_only\":{\"label\":\"Ogranicz tylko do promowanych wydarze\\u0144\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-featured_events_only\",\"name\":\"widget-tribe-widget-events-list[-1][featured_events_only]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"jsonld_enable\":{\"label\":\"Generuj dane JSON-LD\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-jsonld_enable\",\"name\":\"widget-tribe-widget-events-list[-1][jsonld_enable]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"venue\":true,\"country\":false,\"street\":false,\"city\":false,\"region\":false,\"zip\":false,\"phone\":false,\"cost\":false,\"organizer\":false,\"website\":false,\"operand\":\"OR\",\"filters\":\"{\\\"tribe_events_cat\\\":[\\\"70\\\",\\\"323\\\"]}\",\"events\":[10005823,10005836,10005837,10005838,10005839,10006136,10006137,10007311,10006138,10006139,10006140,10006141,10006142,10006143,10006144,10006145,10006147,10006148,10006149,10006150,10006151,10006152,10006153,10006154,10006155,10006156,10006157,10006158,10006159,10006160,10006161],\"url\":\"https:\\\/\\\/cyrkus.eu\\\/pl\\\/?post_type=tribe_events&eventDisplay=widget-events-list\",\"url_event_date\":false,\"bar\":{\"keyword\":\"\",\"date\":\"\"},\"today\":\"2026-09-02 00:00:00\",\"now\":\"2026-09-02 11:43:46\",\"home_url\":\"https:\\\/\\\/cyrkus.eu\\\/pl\\\/\",\"rest_url\":\"https:\\\/\\\/cyrkus.eu\\\/pl\\\/wp-json\\\/tribe\\\/views\\\/v2\\\/html\",\"rest_method\":\"GET\",\"rest_nonce\":\"\",\"today_url\":\"https:\\\/\\\/cyrkus.eu\\\/pl\\\/?post_type=tribe_events&eventDisplay=widget-events-list&rest_route=%2Fwp%2Fv2%2Fpages%2F12560\",\"today_title\":\"Kliknij, aby wybra\\u0107 dzisiejsz\\u0105 dat\\u0119\",\"today_label\":\"Dzisiaj\",\"prev_label\":\"\",\"next_label\":\"\",\"date_formats\":{\"compact\":\"d.m.Y\",\"month_and_year_compact\":\"m.Y\",\"month_and_year\":\"F Y\",\"time_range_separator\":\" - \",\"date_time_separator\":\" |\"},\"messages\":[],\"start_of_week\":\"1\",\"header_title\":\"\",\"header_title_element\":\"h1\",\"content_title\":\"\",\"show_content_title\":false,\"breadcrumbs\":[],\"backlink\":false,\"before_events\":\"\",\"after_events\":\"\\n<!--\\nThis calendar is powered by The Events Calendar.\\nhttp:\\\/\\\/evnt.is\\\/18wn\\n-->\\n\",\"display_events_bar\":false,\"disable_event_search\":true,\"live_refresh\":true,\"ical\":{\"display_link\":true,\"link\":{\"url\":\"https:\\\/\\\/cyrkus.eu\\\/pl\\\/?post_type=tribe_events&#038;eventDisplay=widget-events-list&#038;ical=1\",\"text\":\"Eksportuj Wydarzenia\",\"title\":\"U\\u017cyj tego, aby udost\\u0119pni\\u0107 dane kalendarza z Google Calendar, Apple iCal i innych kompatybilnych aplikacji\"}},\"container_classes\":[\"tribe-common\",\"tribe-events\",\"tribe-events-view\",\"tribe-events-view--widget-events-list\",\"tribe-events-widget\"],\"container_data\":[],\"is_past\":false,\"breakpoints\":{\"xsmall\":500,\"medium\":768,\"full\":960},\"breakpoint_pointer\":\"92116ed2-e88b-49a7-b34f-5ad72390eae3\",\"is_initial_load\":false,\"public_views\":{\"month\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Month_View\",\"view_url\":\"https:\\\/\\\/cyrkus.eu\\\/pl\\\/wydarzenia\\\/month\\\/\",\"view_label\":\"Miesiac\",\"aria_label\":\"Wy\\u015bwietl Wydarzenia w widoku Miesiac\"}},\"show_latest_past\":false,\"past\":false,\"compatibility_classes\":[\"tribe-compatibility-container\"],\"view_more_text\":\"Zobacz kalendarz\",\"view_more_title\":\"Zobacz wi\\u0119cej wydarzenia.\",\"view_more_link\":\"https:\\\/\\\/cyrkus.eu\\\/pl\\\/wydarzenia\\\/\",\"widget_title\":\"Kolejne Terminy\",\"hide_if_no_upcoming_events\":true,\"display\":{\"cost\":false,\"venue\":true,\"street\":false,\"city\":false,\"region\":false,\"zip\":false,\"country\":false,\"phone\":false,\"organizer\":false,\"website\":false},\"subscribe_links\":{\"gcal\":{\"label\":\"Kalendarz Google\",\"single_label\":\"Dodaj do kalendarza Google\",\"visible\":true,\"block_slug\":\"hasGoogleCalendar\"},\"ical\":{\"label\":\"iKalendarz\",\"single_label\":\"Dodaj do iCalendar\",\"visible\":true,\"block_slug\":\"hasiCal\"},\"outlook-365\":{\"label\":\"Outlook 365\",\"single_label\":\"Outlook 365\",\"visible\":true,\"block_slug\":\"hasOutlook365\"},\"outlook-live\":{\"label\":\"Outlook na \\u017cywo\",\"single_label\":\"Outlook na \\u017cywo\",\"visible\":true,\"block_slug\":\"hasOutlookLive\"},\"ics\":{\"label\":\"Eksportuj jako plik .ics\",\"single_label\":\"Eksportuj jako plik .ics\",\"visible\":true,\"block_slug\":null},\"outlook-ics\":{\"label\":\"Eksportuj plik Outlook .ics\",\"single_label\":\"Eksportuj plik Outlook .ics\",\"visible\":true,\"block_slug\":null}},\"display_recurring_toggle\":false,\"_context\":{\"slug\":\"widget-events-list\"}}<\/script>\n\n\t\t\t\t\t\t\t<header class=\"tribe-events-widget-events-list__header\">\n\t\t\t\t\t<h2 class=\"tribe-events-widget-events-list__header-title tribe-common-h6 tribe-common-h--alt\">\n\t\t\t\t\t\tKolejne Terminy\t\t\t\t\t<\/h2>\n\t\t\t\t<\/header>\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"tribe-events-widget-events-list__events\">\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row tribe-events-widget-events-list__event-row--featured\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-07\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\twrz\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t7\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10005823 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-akrobatyka tribe_events_cat-babycyrkus tribe_events_cat-cyrkusband-pl tribe_events_cat-damuna-laguna-pl tribe_events_cat-grupa-performerska tribe_events_cat-klaunada tribe_events_cat-luftakrobatik-pl-3 tribe_events_cat-monocykl-pl tribe_events_cat-rozmaitosci-mlodziezowe tribe_events_cat-scenografia tribe_events_cat-wystepy-pl tribe_events_cat-zabawy-cyrkussowe tribe_events_cat-zonglerka tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t<em class=\"tribe-events-widget-events-list__event-datetime-featured-icon\">\n\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--featured tribe-events-widget-events-list__event-datetime-featured-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 8 10\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0 0h8v10L4.049 7.439 0 10V0z\"\/>\n<\/svg>\n<\/em>\n<span class=\"tribe-events-widget-events-list__event-datetime-featured-text tribe-common-a11y-visual-hide\">\n\tWyr\u00f3\u017cnione<\/span>\n\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-07\">\n\t\t<span class=\"tribe-event-date-start\">15:00<\/span> &#8211; <span class=\"tribe-event-time\">18:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/cyrkus-tydzien-otwartych-drzwi\/\"\n\t\taria-label=\"Event series: CYRKUS-TYDZIE\u0143 OTWARTYCH DRZWI\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/cyrkus-schnupperwoche\/2026-09-07\/\"\n\t\ttitle=\"CYRKUS-TYDZIE\u0143 OTWARTYCH DRZWI\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tCYRKUS-TYDZIE\u0143 OTWARTYCH DRZWI\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row tribe-events-widget-events-list__event-row--featured\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-08\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\twrz\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t8\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10005836 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-akrobatyka tribe_events_cat-babycyrkus tribe_events_cat-cyrkusband-pl tribe_events_cat-damuna-laguna-pl tribe_events_cat-grupa-performerska tribe_events_cat-klaunada tribe_events_cat-luftakrobatik-pl-3 tribe_events_cat-monocykl-pl tribe_events_cat-rozmaitosci-mlodziezowe tribe_events_cat-scenografia tribe_events_cat-wystepy-pl tribe_events_cat-zabawy-cyrkussowe tribe_events_cat-zonglerka tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t<em class=\"tribe-events-widget-events-list__event-datetime-featured-icon\">\n\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--featured tribe-events-widget-events-list__event-datetime-featured-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 8 10\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0 0h8v10L4.049 7.439 0 10V0z\"\/>\n<\/svg>\n<\/em>\n<span class=\"tribe-events-widget-events-list__event-datetime-featured-text tribe-common-a11y-visual-hide\">\n\tWyr\u00f3\u017cnione<\/span>\n\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-08\">\n\t\t<span class=\"tribe-event-date-start\">15:00<\/span> &#8211; <span class=\"tribe-event-time\">18:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/cyrkus-tydzien-otwartych-drzwi\/\"\n\t\taria-label=\"Event series: CYRKUS-TYDZIE\u0143 OTWARTYCH DRZWI\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/cyrkus-schnupperwoche\/2026-09-08\/\"\n\t\ttitle=\"CYRKUS-TYDZIE\u0143 OTWARTYCH DRZWI\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tCYRKUS-TYDZIE\u0143 OTWARTYCH DRZWI\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row tribe-events-widget-events-list__event-row--featured\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-09\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\twrz\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t9\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10005837 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-akrobatyka tribe_events_cat-babycyrkus tribe_events_cat-cyrkusband-pl tribe_events_cat-damuna-laguna-pl tribe_events_cat-grupa-performerska tribe_events_cat-klaunada tribe_events_cat-luftakrobatik-pl-3 tribe_events_cat-monocykl-pl tribe_events_cat-rozmaitosci-mlodziezowe tribe_events_cat-scenografia tribe_events_cat-wystepy-pl tribe_events_cat-zabawy-cyrkussowe tribe_events_cat-zonglerka tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t<em class=\"tribe-events-widget-events-list__event-datetime-featured-icon\">\n\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--featured tribe-events-widget-events-list__event-datetime-featured-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 8 10\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0 0h8v10L4.049 7.439 0 10V0z\"\/>\n<\/svg>\n<\/em>\n<span class=\"tribe-events-widget-events-list__event-datetime-featured-text tribe-common-a11y-visual-hide\">\n\tWyr\u00f3\u017cnione<\/span>\n\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-09\">\n\t\t<span class=\"tribe-event-date-start\">15:00<\/span> &#8211; <span class=\"tribe-event-time\">18:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/cyrkus-tydzien-otwartych-drzwi\/\"\n\t\taria-label=\"Event series: CYRKUS-TYDZIE\u0143 OTWARTYCH DRZWI\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/cyrkus-schnupperwoche\/2026-09-09\/\"\n\t\ttitle=\"CYRKUS-TYDZIE\u0143 OTWARTYCH DRZWI\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tCYRKUS-TYDZIE\u0143 OTWARTYCH DRZWI\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row tribe-events-widget-events-list__event-row--featured\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-10\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\twrz\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t10\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10005838 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-akrobatyka tribe_events_cat-babycyrkus tribe_events_cat-cyrkusband-pl tribe_events_cat-damuna-laguna-pl tribe_events_cat-grupa-performerska tribe_events_cat-klaunada tribe_events_cat-luftakrobatik-pl-3 tribe_events_cat-monocykl-pl tribe_events_cat-rozmaitosci-mlodziezowe tribe_events_cat-scenografia tribe_events_cat-wystepy-pl tribe_events_cat-zabawy-cyrkussowe tribe_events_cat-zonglerka tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t<em class=\"tribe-events-widget-events-list__event-datetime-featured-icon\">\n\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--featured tribe-events-widget-events-list__event-datetime-featured-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 8 10\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0 0h8v10L4.049 7.439 0 10V0z\"\/>\n<\/svg>\n<\/em>\n<span class=\"tribe-events-widget-events-list__event-datetime-featured-text tribe-common-a11y-visual-hide\">\n\tWyr\u00f3\u017cnione<\/span>\n\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-10\">\n\t\t<span class=\"tribe-event-date-start\">15:00<\/span> &#8211; <span class=\"tribe-event-time\">18:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/cyrkus-tydzien-otwartych-drzwi\/\"\n\t\taria-label=\"Event series: CYRKUS-TYDZIE\u0143 OTWARTYCH DRZWI\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/cyrkus-schnupperwoche\/2026-09-10\/\"\n\t\ttitle=\"CYRKUS-TYDZIE\u0143 OTWARTYCH DRZWI\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tCYRKUS-TYDZIE\u0143 OTWARTYCH DRZWI\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row tribe-events-widget-events-list__event-row--featured\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-11\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\twrz\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t11\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10005839 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-akrobatyka tribe_events_cat-babycyrkus tribe_events_cat-cyrkusband-pl tribe_events_cat-damuna-laguna-pl tribe_events_cat-grupa-performerska tribe_events_cat-klaunada tribe_events_cat-luftakrobatik-pl-3 tribe_events_cat-monocykl-pl tribe_events_cat-rozmaitosci-mlodziezowe tribe_events_cat-scenografia tribe_events_cat-wystepy-pl tribe_events_cat-zabawy-cyrkussowe tribe_events_cat-zonglerka tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t<em class=\"tribe-events-widget-events-list__event-datetime-featured-icon\">\n\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--featured tribe-events-widget-events-list__event-datetime-featured-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 8 10\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0 0h8v10L4.049 7.439 0 10V0z\"\/>\n<\/svg>\n<\/em>\n<span class=\"tribe-events-widget-events-list__event-datetime-featured-text tribe-common-a11y-visual-hide\">\n\tWyr\u00f3\u017cnione<\/span>\n\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-11\">\n\t\t<span class=\"tribe-event-date-start\">15:00<\/span> &#8211; <span class=\"tribe-event-time\">18:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/cyrkus-tydzien-otwartych-drzwi\/\"\n\t\taria-label=\"Event series: CYRKUS-TYDZIE\u0143 OTWARTYCH DRZWI\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/cyrkus-schnupperwoche\/2026-09-11\/\"\n\t\ttitle=\"CYRKUS-TYDZIE\u0143 OTWARTYCH DRZWI\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tCYRKUS-TYDZIE\u0143 OTWARTYCH DRZWI\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-14\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\twrz\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t14\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006136 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-14\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-09-14\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-21\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\twrz\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t21\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006137 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-21\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-09-21\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-28\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\twrz\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t28\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10007311 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-28\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-09-28\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-10-05\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tpa\u017a\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t5\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006138 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-10-05\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-10-05\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-10-26\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tpa\u017a\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t26\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006139 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-10-26\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-10-26\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-11-02\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tlis\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t2\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006140 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-11-02\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-11-02\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-11-09\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tlis\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t9\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006141 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-11-09\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-11-09\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-11-16\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tlis\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t16\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006142 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-11-16\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-11-16\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-11-23\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tlis\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t23\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006143 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-11-23\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-11-23\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-11-30\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tlis\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t30\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006144 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-11-30\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-11-30\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-12-07\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tgru\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t7\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006145 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-12-07\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2026-12-07\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2027-01-11\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tsty\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t11\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006147 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2027-01-11\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-01-11\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2027-01-18\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tsty\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t18\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006148 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2027-01-18\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-01-18\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2027-01-25\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tsty\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t25\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006149 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2027-01-25\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-01-25\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2027-02-01\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tlut\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t1\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006150 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2027-02-01\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-02-01\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2027-02-22\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tlut\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t22\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006151 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2027-02-22\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-02-22\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2027-03-01\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tmar\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t1\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006152 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2027-03-01\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-03-01\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2027-03-08\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tmar\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t8\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006153 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2027-03-08\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-03-08\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2027-03-15\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tmar\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t15\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006154 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2027-03-15\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-03-15\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2027-03-22\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tmar\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t22\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006155 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2027-03-22\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-03-22\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2027-04-05\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tkwi\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t5\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006156 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2027-04-05\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-04-05\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2027-04-12\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tkwi\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t12\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006157 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2027-04-12\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-04-12\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2027-04-19\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tkwi\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t19\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006158 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2027-04-19\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-04-19\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2027-04-26\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tkwi\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t26\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006159 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2027-04-26\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-04-26\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2027-05-03\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tmaj\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t3\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006160 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2027-05-03\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-05-03\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2027-05-10\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tmaj\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t10\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10006161 tribe_events type-tribe_events status-publish has-post-thumbnail tribe_events_cat-grupa-performerska tribe-recurring-event tribe-recurring-event-parent\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2027-05-10\">\n\t\t<span class=\"tribe-event-date-start\">17:30<\/span> &#8211; <span class=\"tribe-event-time\">19:30<\/span>\t<\/time>\n\t\n<span class=\"tribe-events-calendar-series-archive__container\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/serie\/grupa-performerska\/\"\n\t\taria-label=\"Event series: Grupa performerska\"\n\t\tclass=\"tribe-events-calendar-series-archive__link\"\n\t>\n\t\t\n<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--series tribe-events-series-archive__icon\"  width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\">\n\t<rect x=\"0.5\" y=\"4.5\" width=\"9\" height=\"7\" \/>\n\t<path d=\"M2 2.5H11.5V10\" \/>\n\t<path d=\"M4 0.5H13.5V8\" \/>\n<\/svg>\n\t<\/a>\n<\/span>\n<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/event\/performence-group\/2027-05-10\/\"\n\t\ttitle=\"Grupa performerska\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tGrupa performerska\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t<div class=\"tribe-common-b2 tribe-events-widget-events-list__event-venue\">\n\n\t\t\t<a\n\t\t\thref=\"https:\/\/cyrkus.eu\/miejsce-wydarzenia\/cyrkus-domicil\/\"\n\t\t\tclass=\"tribe-common-b2--bold tribe-common-anchor-thin tribe-events-widget-events-list__event-venue-name\"\n\t\t>\n\t\t\tCYRKUS DOMicil\t\t<\/a>\n\t\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"tribe-events-widget-events-list__view-more tribe-common-b1 tribe-common-b2--min-medium\">\n\t<a\n\t\thref=\"https:\/\/cyrkus.eu\/pl\/wydarzenia\/\"\n\t\tclass=\"tribe-events-widget-events-list__view-more-link tribe-common-anchor-thin\"\n\t\ttitle=\"Zobacz wi\u0119cej wydarzenia.\"\n\t>\n\t\tZobacz kalendarz\t<\/a>\n<\/div>\n\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<script data-js='tribe-events-view-nonce-data' type='application\/json'>{\"tvn1\":\"64e6ef96e2\",\"tvn2\":\"\"}<\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Grupa performerska Grupa Performerska to warsztat skierowany do dzieci i m\u0142odzie\u017cy, kt\u00f3re maj\u0105 ju\u017c do\u015bwiadczenie &#8230; <a title=\"Grupa performerska\" class=\"read-more\" href=\"https:\/\/cyrkus.eu\/pl\/grupa-performerska\/\" aria-label=\"Dowiedz si\u0119 wi\u0119cej o Grupa performerska\">Czytaj dalej<\/a><\/p>\n","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12560","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/cyrkus.eu\/pl\/wp-json\/wp\/v2\/pages\/12560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyrkus.eu\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cyrkus.eu\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cyrkus.eu\/pl\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cyrkus.eu\/pl\/wp-json\/wp\/v2\/comments?post=12560"}],"version-history":[{"count":1,"href":"https:\/\/cyrkus.eu\/pl\/wp-json\/wp\/v2\/pages\/12560\/revisions"}],"predecessor-version":[{"id":12568,"href":"https:\/\/cyrkus.eu\/pl\/wp-json\/wp\/v2\/pages\/12560\/revisions\/12568"}],"wp:attachment":[{"href":"https:\/\/cyrkus.eu\/pl\/wp-json\/wp\/v2\/media?parent=12560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}